{"id":5209,"date":"2016-08-17T19:19:26","date_gmt":"2016-08-17T17:19:26","guid":{"rendered":"http:\/\/jetskede.trinos.nl\/?p=5209"},"modified":"2023-03-03T11:20:56","modified_gmt":"2023-03-03T11:20:56","slug":"lsf-sonnencreme-make-up","status":"publish","type":"post","link":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/","title":{"rendered":"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen?"},"content":{"rendered":"<h3><strong>Bietet meine Foundation ausreichend Schutz vor Sonnensch\u00e4den?<\/strong><\/h3>\n<p>Eine Foundation mit LSF 30 sch\u00fctzt Ihre Haut genauso gut vor Sonnensch\u00e4den wie eine \u201enormale\u201c Sonnencreme &#8211; die Sache hat jedoch einen Haken: Um den auf der Verpackung angegebenen Schutzfaktor zu erreichen, m\u00fcssen Sie n\u00e4mlich eine dicke Schicht des Produkts auftragen, was bei einer Foundation kein allzu sch\u00f6nes Ergebnis erzielt! Wenn Sie mich fragen, ist eine Foundation mit LSF gut geeignet, um Ihre Haut im Winter zu sch\u00fctzen, wenn der UV-Index niedrig ist und Sie sich viel in Geb\u00e4uden aufhalten. F\u00fcr das restliche Jahr ersetzt sie die Sonnencreme jedoch nicht.<\/p>\n<h3><strong>Darf man die Foundation mit Sonnencreme mischen?<\/strong><\/h3>\n<p>Nat\u00fcrlich \u201ed\u00fcrfen\u201c Sie Ihre Foundation mit Sonnencreme mischen, aber wirklich vern\u00fcnftig ist das nicht. Eines sollten Sie n\u00e4mlich bedenken: Wenn der LSF in Ihrer Foundation niedriger ist als der in Ihrer Sonnencreme, wird sich der Schutz dieser Mischung letztendlich deutlich reduzieren. Die Konzentration der UV-Filter in der Mischung ist schlie\u00dflich niedriger als in Ihrer Sonnencreme. Hinzu kommt noch das Risiko, dass die Wirksamkeit der UV-Filter durch das Mischen der Produkte beeintr\u00e4chtigt wird. Chemische Filter wie Avobenzon, Oxybenzon und Homosalat sind beispielsweise sehr instabil, wodurch Sie sich nicht sicher sein k\u00f6nnen, wie gut Sie gesch\u00fctzt sind. Zwei separate Schichten sind also besser!<\/p>\n<p><a href=\"https:\/\/www.dr-jetskeultee.de\/produkte\/suncover-sonnencreme.html?utm_source=blog&amp;utm_medium=banner&amp;utm_campaign=inblogbanner_suncover\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7508 size-full\" src=\"https:\/\/www.dr-jetskeultee.de\/blog\/wp-content\/uploads\/sites\/2\/2016\/08\/Banner_Sonnencreme.png\" alt=\"\" width=\"640\" height=\"355\" srcset=\"https:\/\/www.dr-jetskeultee.de\/blog\/wp-content\/uploads\/sites\/2\/2016\/08\/Banner_Sonnencreme.png 640w, https:\/\/www.dr-jetskeultee.de\/blog\/wp-content\/uploads\/sites\/2\/2016\/08\/Banner_Sonnencreme-300x166.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<h3><strong>M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen?<\/strong><\/h3>\n<p>Tragen Sie Sonnencreme besser unter Ihrem Make-up auf, jedoch \u00fcber der Feuchtigkeitscreme. Die wichtigen Inhaltsstoffe in der Feuchtigkeitscreme k\u00f6nnen n\u00e4mlich weniger gut wirken, wenn Sie die Reihenfolge \u00e4ndern. Die beste Kombination ist eine Feuchtigkeitscreme mit Antioxidantien und dar\u00fcber die Sonnencreme, vor allem, wenn diese auch noch Antioxidantien enth\u00e4lt. Sie sollten jedoch eine Feuchtigkeitscreme auf Wasserbasis verwenden. Eine solche k\u00f6nnen Sie einfach erkennen: Auf der Liste der Inhaltsstoffe steht dann als erstes aqua. Ein sehr fettiges Produkt kann n\u00e4mlich daf\u00fcr sorgen, dass die Sonnencreme nicht einzieht. Und das ist insbesondere bei chemischen UV-Filtern ein Problem. Lassen Sie die Sonnencreme dann mindestens eine Viertelstunde \u201eeinwirken\u201c. Im Anschluss k\u00f6nnen Sie Ihr Make-up auftragen.<\/p>\n<h3><strong>Kann man Sonnencreme beim erneuten Eincremen auf das Make-up auftragen?<\/strong><\/h3>\n<p>Wenn Sie sich wirklich an die Empfehlungen halten m\u00f6chten, m\u00fcssen Sie sich alle zwei Stunden erneut eincremen, was nicht nur schwierig ist, wenn man Make-up tr\u00e4gt, sondern sich aufgrund voller Terminkalender auch nicht immer realisieren l\u00e4sst. Sie sollten dann auf jeden Fall in eine gute Sonnencreme f\u00fcr Ihr Gesicht mit modernen und stabilen physikalischen oder semi-physikalischen UV-Filtern wie Tinosorb investieren. Dann ist Ihre Haut auch nach einigen Stunden noch gut gesch\u00fctzt und laufen Sie nicht das Risiko, dass die Sonnencreme nicht gut genug einziehen kann, wenn Sie sie erneut auftragen. Sie k\u00f6nnen auch Puder mit LSF auffrischen, sollten sich dann aber bewusst sein, dass Sie damit nur einen eingeschr\u00e4nkten Schutz aufbauen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Herzliche Gr\u00fc\u00dfe<\/p>\n<p>Jetske Ultee<\/p>\n<p><em>(Forschungs\u00e4rztin kosmetische Dermatologie)<\/em><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Lesen sie auch:<\/strong><\/h3>\n<p><a href=\"https:\/\/www.dr-jetskeultee.de\/produkte\/sonnencremes.html?utm_source=blog&amp;utm_medium=M%C3%BCssen+Sie+die+Sonnencreme+unter+oder+%C3%BCber+Ihrer+Kosmetik+auftragen%3F&amp;utm_campaign=Sonnencremes\" target=\"_blank\" rel=\"noopener\">Meine Sonnencremes<\/a><br \/>\n<a href=\"https:\/\/www.dr-jetskeultee.de\/blog\/sonne-creme-hilfe-wahl\/\" target=\"_blank\" rel=\"noopener\">Hilfe bei der Wahl Ihrer Sonnencreme<\/a><br \/>\n<a href=\"https:\/\/www.dr-jetskeultee.de\/blog\/produktempfehlung-foundation\/\" target=\"_blank\" rel=\"noopener\">Produktempfehlung Foundation<\/a><br \/>\n<a href=\"https:\/\/www.dr-jetskeultee.de\/blog\/bb-cream-hot-not\/\" target=\"_blank\" rel=\"noopener\">BB-Cream, hot or not?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bietet meine Foundation ausreichend Schutz vor Sonnensch\u00e4den?<br \/>\nEine Foundation mit LSF 30 sch\u00fctzt Ihre Haut genauso gut vor Sonnensch\u00e4den wie eine \u201enormale\u201c Sonnencreme &#8211; die Sache hat jedoch einen Haken: Um den auf der Verpackung angegebenen Schutzfaktor zu erreichen, m\u00fcssen Sie n\u00e4mlich eine dicke Schicht des Produkts auftragen, was bei einer Foundation kein allzu sch\u00f6nes Ergebnis erzielt! Wenn Sie mich fragen, ist eine Foundation mit LSF gut geeignet, um Ihre Haut im Winter zu sch\u00fctzen, wenn der UV-Index niedrig ist und Sie sich viel in Geb\u00e4uden aufhalten. F\u00fcr das restliche Jahr ersetzt sie die Sonnencreme jedoch nicht.<\/p>\n","protected":false},"author":2,"featured_media":7645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9,23,24,26],"tags":[354,121,138,186,279,281,282,284,311],"class_list":["post-5209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hautpflege","category-make-up","category-schutzen","category-sonne","category-sonnenschutz","tag-bansc","tag-foundation","tag-hautalterung","tag-make-up","tag-sonne","tag-sonnenbrand","tag-sonnencreme","tag-sonnenschutz","tag-uv-strahlen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee<\/title>\n<meta name=\"description\" content=\"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee\" \/>\n<meta property=\"og:description\" content=\"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Jetske Ultee\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-17T17:19:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T11:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dr-jetskeultee.de\/blog\/wp-content\/uploads\/sites\/2\/2016\/08\/92_Foundation_zonnebrandcreme.png\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dr. Jetske Ultee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Jetske Ultee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/\",\"url\":\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/\",\"name\":\"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee\",\"isPartOf\":{\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/#website\"},\"datePublished\":\"2016-08-17T17:19:26+00:00\",\"dateModified\":\"2023-03-03T11:20:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/e1e8d176edca9536cdd3a7d126e306f2\"},\"description\":\"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.dr-jetskeultee.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/#website\",\"url\":\"https:\/\/www.dr-jetskeultee.de\/blog\/\",\"name\":\"Dr. Jetske Ultee\",\"description\":\"Der Blog \u00fcber Hautpflege\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dr-jetskeultee.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/e1e8d176edca9536cdd3a7d126e306f2\",\"name\":\"Dr. Jetske Ultee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/46ffda69651762f1ef3ca8678144ba45c1f6fa3b464283ef5430099b8c6b0655?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/46ffda69651762f1ef3ca8678144ba45c1f6fa3b464283ef5430099b8c6b0655?s=96&d=mm&r=g\",\"caption\":\"Dr. Jetske Ultee\"},\"url\":\"https:\/\/www.dr-jetskeultee.de\/blog\/author\/jetske\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee","description":"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee","og_description":"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!","og_url":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/","og_site_name":"Dr. Jetske Ultee","article_published_time":"2016-08-17T17:19:26+00:00","article_modified_time":"2023-03-03T11:20:56+00:00","og_image":[{"width":590,"height":295,"url":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-content\/uploads\/sites\/2\/2016\/08\/92_Foundation_zonnebrandcreme.png","type":"image\/png"}],"author":"Dr. Jetske Ultee","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dr. Jetske Ultee","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/","url":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/","name":"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen? - Dr. Jetske Ultee","isPartOf":{"@id":"https:\/\/www.dr-jetskeultee.de\/blog\/#website"},"datePublished":"2016-08-17T17:19:26+00:00","dateModified":"2023-03-03T11:20:56+00:00","author":{"@id":"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/e1e8d176edca9536cdd3a7d126e306f2"},"description":"Ist Foundation mit LSF geeignet, um Ihre Haut zu sch\u00fctzen? Nur wenn der UV-Index niedrig ist und Sie sich viel innen aufhalten-f\u00fcr das restliche Jahr nicht!","breadcrumb":{"@id":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dr-jetskeultee.de\/blog\/lsf-sonnencreme-make-up\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.dr-jetskeultee.de\/blog\/"},{"@type":"ListItem","position":2,"name":"M\u00fcssen Sie die Sonnencreme unter oder \u00fcber Ihrer Kosmetik auftragen?"}]},{"@type":"WebSite","@id":"https:\/\/www.dr-jetskeultee.de\/blog\/#website","url":"https:\/\/www.dr-jetskeultee.de\/blog\/","name":"Dr. Jetske Ultee","description":"Der Blog \u00fcber Hautpflege","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dr-jetskeultee.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/e1e8d176edca9536cdd3a7d126e306f2","name":"Dr. Jetske Ultee","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.dr-jetskeultee.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/46ffda69651762f1ef3ca8678144ba45c1f6fa3b464283ef5430099b8c6b0655?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46ffda69651762f1ef3ca8678144ba45c1f6fa3b464283ef5430099b8c6b0655?s=96&d=mm&r=g","caption":"Dr. Jetske Ultee"},"url":"https:\/\/www.dr-jetskeultee.de\/blog\/author\/jetske\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/posts\/5209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/comments?post=5209"}],"version-history":[{"count":18,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/posts\/5209\/revisions"}],"predecessor-version":[{"id":10692,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/posts\/5209\/revisions\/10692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/media\/7645"}],"wp:attachment":[{"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/media?parent=5209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/categories?post=5209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dr-jetskeultee.de\/blog\/wp-json\/wp\/v2\/tags?post=5209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}